{"id":647,"count":6,"description":"","link":"https:\/\/beautifultrollcosmetics.com\/el\/product-category\/pure-oils\/","name":"\u039a\u0391\u0398\u0391\u03a1\u0391 \u0395\u039b\u0391\u0399\u0391","slug":"pure-oils","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/beautifultrollcosmetics.com\/el\/product-category\/pure-oils\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/647\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/shop-full-width\\\/#listItem\",\"name\":\"Shop Full Width\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/shop-full-width\\\/#listItem\",\"position\":2,\"name\":\"Shop Full Width\",\"item\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/shop-full-width\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/product-category\\\/pure-oils\\\/#listItem\",\"name\":\"PURE OILS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/product-category\\\/pure-oils\\\/#listItem\",\"position\":3,\"name\":\"PURE OILS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/shop-full-width\\\/#listItem\",\"name\":\"Shop Full Width\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/647\\\/#collectionpage\",\"url\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/647\\\/\",\"name\":\"PURE OILS - Beautiful Troll Cosmetics\",\"inLanguage\":\"el\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/647\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/#organization\",\"name\":\"Beautiful Troll Comsetics\",\"description\":\"Skin food products\",\"url\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/\",\"telephone\":\"+35794089400\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/BTC-LOGO-2022.png\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/647\\\/#organizationLogo\",\"width\":913,\"height\":685},\"image\":{\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/647\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beautifultrollcosmetics\\\/\",\"https:\\\/\\\/twitter.com\\\/beautifultrollc\",\"https:\\\/\\\/www.instagram.com\\\/beautifultrollcosmetics\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beautifultrollcosmetics\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/\",\"name\":\"Beautiful Troll Cosmetics\",\"alternateName\":\"Vegan Premium Cosmetics - Cutting-Edge Formulas\",\"description\":\"Skin food products\",\"inLanguage\":\"el\",\"publisher\":{\"@id\":\"https:\\\/\\\/beautifultrollcosmetics.com\\\/el\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"PURE OILS - Beautiful Troll Cosmetics","description":"","canonical_url":"https:\/\/beautifultrollcosmetics.com\/el\/product-category\/pure-oils\/","robots":"noindex, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el#listItem","position":1,"name":"Home","item":"https:\/\/beautifultrollcosmetics.com\/el","nextItem":{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el\/shop-full-width\/#listItem","name":"Shop Full Width"}},{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el\/shop-full-width\/#listItem","position":2,"name":"Shop Full Width","item":"https:\/\/beautifultrollcosmetics.com\/el\/shop-full-width\/","nextItem":{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el\/product-category\/pure-oils\/#listItem","name":"PURE OILS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el\/product-category\/pure-oils\/#listItem","position":3,"name":"PURE OILS","previousItem":{"@type":"ListItem","@id":"https:\/\/beautifultrollcosmetics.com\/el\/shop-full-width\/#listItem","name":"Shop Full Width"}}]},{"@type":"CollectionPage","@id":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647\/#collectionpage","url":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647\/","name":"PURE OILS - Beautiful Troll Cosmetics","inLanguage":"el","isPartOf":{"@id":"https:\/\/beautifultrollcosmetics.com\/el\/#website"},"breadcrumb":{"@id":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/beautifultrollcosmetics.com\/el\/#organization","name":"Beautiful Troll Comsetics","description":"Skin food products","url":"https:\/\/beautifultrollcosmetics.com\/el\/","telephone":"+35794089400","logo":{"@type":"ImageObject","url":"https:\/\/beautifultrollcosmetics.com\/wp-content\/uploads\/2022\/04\/BTC-LOGO-2022.png","@id":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647\/#organizationLogo","width":913,"height":685},"image":{"@id":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/beautifultrollcosmetics\/","https:\/\/twitter.com\/beautifultrollc","https:\/\/www.instagram.com\/beautifultrollcosmetics\/","https:\/\/www.linkedin.com\/company\/beautifultrollcosmetics\/"]},{"@type":"WebSite","@id":"https:\/\/beautifultrollcosmetics.com\/el\/#website","url":"https:\/\/beautifultrollcosmetics.com\/el\/","name":"Beautiful Troll Cosmetics","alternateName":"Vegan Premium Cosmetics - Cutting-Edge Formulas","description":"Skin food products","inLanguage":"el","publisher":{"@id":"https:\/\/beautifultrollcosmetics.com\/el\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/beautifultrollcosmetics.com\/el\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/beautifultrollcosmetics.com\/el\/shop-full-width\/\" title=\"Shop Full Width\">Shop Full Width<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPURE OILS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/beautifultrollcosmetics.com\/el"},{"label":"Shop Full Width","link":"https:\/\/beautifultrollcosmetics.com\/el\/shop-full-width\/"},{"label":"PURE OILS","link":"https:\/\/beautifultrollcosmetics.com\/el\/product-category\/pure-oils\/"}],"_links":{"self":[{"href":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/beautifultrollcosmetics.com\/el\/wp-json\/wp\/v2\/product?product_cat=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}